{"id":30528,"date":"2026-02-24T12:23:37","date_gmt":"2026-02-24T12:23:37","guid":{"rendered":"https:\/\/intoconcept.com\/?post_type=reference&#038;p=30528"},"modified":"2026-06-22T08:58:42","modified_gmt":"2026-06-22T08:58:42","slug":"consulenza-cintura-nera","status":"publish","type":"reference","link":"https:\/\/intoconcept.com\/it\/referenssi\/black-belt-consulting\/","title":{"rendered":"Consulenza Black Belt"},"content":{"rendered":"<h2>Contesto<\/h2>\n<p><span data-contrast=\"auto\"><a href=\"https:\/\/blackbelts.fi\/\" target=\"_blank\" rel=\"noopener\">Consulenza Black Belt<\/a> \u00e8 una societ\u00e0 finlandese di consulenza informatica fondata nel 2022, che combina consulenza informatica e ricerca di personale esperto. L'azienda riunisce esperti IT e aziende e i suoi uffici si trovano a Hakaniemi, Helsinki.<\/span><\/p>\n<h2>Sfida<strong><br \/>\n<\/strong><\/h2>\n<p><span data-ccp-props=\"{}\">Black Belt Consulting era alla ricerca di soluzioni funzionali per le telefonate e lo spazio per le riunioni di pi\u00f9 persone nel proprio ufficio. Era particolarmente importante trovare soluzioni che utilizzassero alternative riciclate e sostenibili.<\/span><\/p>\n<h2>Soluzione<\/h2>\n<p><span data-contrast=\"auto\">L'atrio dell'ufficio \u00e8 stato attrezzato con un sistema di <a href=\"https:\/\/intoconcept.com\/it\/product\/sala-conferenze-pod2\/\">POD 2<\/a> -che funge da sala riunioni flessibile per 2-4 persone. Lo spazio \u00e8 stato arredato con materiali riciclati <a href=\"https:\/\/intoconcept.com\/it\/product\/punto-divani-bassi\/\">PUNTO BASSO<\/a> -divani e <a href=\"https:\/\/intoconcept.com\/it\/product\/top-poyta-2\/\">TOP<\/a>-sul tavolo. I divani POINT LOW sono progettati con le dimensioni di una sedia da scrivania, rendendo ergonomica la seduta per lunghi periodi e il lavoro in tutta comodit\u00e0.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-30633 size-large\" src=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-1024x768.jpg\" alt=\"POD 2\" width=\"800\" height=\"600\" srcset=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-1024x768.jpg 1024w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-300x225.jpg 300w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-768x576.jpg 768w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-1536x1152.jpg 1536w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251-16x12.jpg 16w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3251.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-30634 size-large\" src=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-1024x768.jpg\" alt=\"POD PHONE\" width=\"800\" height=\"600\" srcset=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-1024x768.jpg 1024w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-300x225.jpg 300w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-768x576.jpg 768w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-1536x1152.jpg 1536w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199-16x12.jpg 16w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/01\/IMG_3199.jpg 2011w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span data-contrast=\"auto\">\u00c8 stato aggiunto un materiale riciclato al lato dell'area di lavoro <a href=\"https:\/\/intoconcept.com\/it\/product\/cabina-telefonica-pod-phone\/\">POD PHONE<\/a> -Cabina telefonica con porta in vetro, che offre uno spazio tranquillo e privato per le chiamate in un ufficio aperto.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Sull'altro lato dell'ufficio sono stati collocati tre <a href=\"https:\/\/intoconcept.com\/it\/product\/cubo-solo-9\/\">CUBO SOLO<\/a> -che hanno immediatamente attirato l'interesse dell'amministratore delegato dell'azienda Sameli M\u00e4enp\u00e4\u00e4 durante la sua visita alla sede di INTO Concept.\u00a0<a href=\"https:\/\/intoconcept.com\/it\/contatto\/\">showroom<\/a>. <\/span>Le sedie erano particolarmente interessanti per la loro privacy, il design insonorizzato e la base girevole. Le sedie sono state posizionate una dietro l'altra e in parte una di fronte all'altra, per migliorare ulteriormente l'isolamento acustico. Tra le sedie, un tavolo regolabile in altezza <a href=\"https:\/\/intoconcept.com\/it\/product\/top-poyta-2\/\">SOLLEVAMENTO SUPERIORE BASSO<\/a> scrivanie per renderle funzionali e autonome.<\/p>\n<h2>Risultati di<\/h2>\n<p>I mobili riciclati di INTO Concept hanno creato tranquillit\u00e0 e hanno permesso a Black Belt Consulting di lavorare in modo versatile. I prodotti offrono privacy, ergonomia e soluzioni funzionali per diverse situazioni di lavoro.<\/p>\n<p><strong>\u201dApprezziamo i partner che sono ai vertici del loro settore, le Cinture Nere. INTO Concept combina il miglior design finlandese, la responsabilit\u00e0 e una forte competenza\u201d.\u201d<\/strong><\/p>\n<p>Sameli M\u00e4enp\u00e4\u00e4, amministratore delegato di Black Belt Consulting<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-31462 size-large\" src=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-1024x768.jpg\" alt=\"CUBO SOLO\" width=\"800\" height=\"600\" srcset=\"https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-1024x768.jpg 1024w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-300x225.jpg 300w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-768x576.jpg 768w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-1536x1152.jpg 1536w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203-16x12.jpg 16w, https:\/\/intoconcept.com\/wp-content\/uploads\/2026\/02\/IMG_3203.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>","protected":false},"featured_media":31463,"parent":0,"template":"","meta":{"_acf_changed":false},"ref_product":[67,64,71,194,177],"ref_product_cat":[77,79,78],"class_list":["post-30528","reference","type-reference","status-publish","has-post-thumbnail","hentry","ref_product-prod-1549","ref_product-prod-1575","ref_product-prod-1589","ref_product-prod-30051","ref_product-prod-29883","ref_product_cat-rcat-21","ref_product_cat-rcat-15","ref_product_cat-rcat-22"],"acf":[],"_links":{"self":[{"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/reference\/30528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/media\/31463"}],"wp:attachment":[{"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/media?parent=30528"}],"wp:term":[{"taxonomy":"ref_product","embeddable":true,"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/ref_product?post=30528"},{"taxonomy":"ref_product_cat","embeddable":true,"href":"https:\/\/intoconcept.com\/it\/wp-json\/wp\/v2\/ref_product_cat?post=30528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}